{"id":775,"count":1,"description":"","link":"https:\/\/puranigaadi.com\/jobs\/tag\/delta-airlines-remote-customer-service-jobs-part-time\/","name":"delta airlines remote customer service jobs part time","slug":"delta-airlines-remote-customer-service-jobs-part-time","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/puranigaadi.com\/jobs\/wp-json\/wp\/v2\/tags\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puranigaadi.com\/jobs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/puranigaadi.com\/jobs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/puranigaadi.com\/jobs\/wp-json\/wp\/v2\/posts?tags=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}